{"id":46,"date":"2011-12-16T01:07:21","date_gmt":"2011-12-16T01:07:21","guid":{"rendered":"http:\/\/www.kriesi.at\/themes\/propulsion\/?post_type=portfolio&amp;p=46"},"modified":"2011-12-16T01:07:21","modified_gmt":"2011-12-16T01:07:21","slug":"slider-two-third","status":"publish","type":"portfolio","link":"https:\/\/dirisukilisesi.org\/index.php\/portfolio-item\/slider-two-third\/","title":{"rendered":"Single Portfolio: 2\/3 Slider"},"content":{"rendered":"<div class='flex_column av-av_two_third-2a9015ff38129c418a3f2eafba3e9512 av_two_third  avia-builder-el-0  el_before_av_one_third  avia-builder-el-first  first flex_column_div '     ><div  class='avia-slideshow av-av_slideshow-caf2cb1a3b7c84933b4199dbc65e8743 avia-slideshow-gallery av_slideshow avia-slide-slider  avia-builder-el-1  avia-builder-el-no-sibling  av-slideshow-ui av-control-default av-slideshow-autoplay av-loop-endless av-loop-manual-endless av-default-height-applied avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:true,&quot;loop_autoplay&quot;:&quot;endless&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 76.923076923077%;'><li  class='avia-slideshow-slide av-av_slideshow-caf2cb1a3b7c84933b4199dbc65e8743__1  slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-315 avia-img-lazy-loading-not-315\"  src=\"https:\/\/dirisukilisesi.org\/wp-content\/uploads\/2012\/04\/014-845x650.jpg\" width=\"845\" height=\"650\" title='014' alt=''  itemprop=\"thumbnailUrl\"   \/><\/div><\/li><li  class='avia-slideshow-slide av-av_slideshow-caf2cb1a3b7c84933b4199dbc65e8743__2  slide-2 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-314 avia-img-lazy-loading-not-314\"  src=\"https:\/\/dirisukilisesi.org\/wp-content\/uploads\/2012\/04\/013-845x650.jpg\" width=\"845\" height=\"650\" title='013' alt=''  itemprop=\"thumbnailUrl\"   \/><\/div><\/li><li  class='avia-slideshow-slide av-av_slideshow-caf2cb1a3b7c84933b4199dbc65e8743__3  slide-3 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-313 avia-img-lazy-loading-not-313\"  src=\"https:\/\/dirisukilisesi.org\/wp-content\/uploads\/2012\/04\/1-845x650.jpg\" width=\"845\" height=\"650\" title='1' alt=''  itemprop=\"thumbnailUrl\"   \/><\/div><\/li><\/ul><div class='avia-slideshow-arrows avia-slideshow-controls' ><a href='#prev' class='prev-slide ' aria-hidden='true' data-av_icon='\ue87c' data-av_iconfont='entypo-fontello'  tabindex='-1'>\u00d6nceki<\/a><a href='#next' class='next-slide ' aria-hidden='true' data-av_icon='\ue87d' data-av_iconfont='entypo-fontello'  tabindex='-1'>Sonraki<\/a><\/div><div class='avia-slideshow-dots avia-slideshow-controls'><a href='#1' class='goto-slide active' >1<\/a><a href='#2' class='goto-slide ' >2<\/a><a href='#3' class='goto-slide ' >3<\/a><\/div><\/div><\/div>\n<div class='flex_column av-av_one_third-f78fb3c186c5ceb3cf0bf54353219056 av_one_third  avia-builder-el-2  el_after_av_two_third  el_before_av_section  avia-builder-el-last  flex_column_div '     ><section  class='av_textblock_section av-av_textblock-e9dae3e5b2541c4b73533e030c1212d3'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h3>Portfolio Entry!<\/h3>\n<p>Nulla\u00a0<strong>consequat<\/strong>\u00a0massa quis enim. Donec pede justo, fringilla vel, aliquet nec, vulputate eget, arcu. In enim justo, rhoncus ut, imperdiet a, venenatis vitae, justo. Nullam dictum felis eu\u00a0<strong>pede<\/strong>\u00a0mollis pretium. Integer tincidunt. Cras dapibus.<\/p>\n<\/div><\/section><br \/>\n<div  class='togglecontainer av-av_toggle_container-9e31e9664926ed42e49207057922aa29  avia-builder-el-4  el_after_av_textblock  avia-builder-el-last  toggle_close_all' >\n<section class='av_toggle_section av-av_toggle-3ba880c992bc3c8fbd4ac950553a40d2'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{T\u00fcm\u00fc} \"  ><p data-fake-id='#toggle-id-1' class='toggler  activeTitle '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-1'>Client<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-1' class='toggle_wrap  active_tc' style='display:block;' ><div class='toggle_content invers-color '  itemprop=\"text\" ><p><strong>XY Media<\/strong><\/p>\n<p>Lorem ipsum dolor sit amet, consectetuer adipiscing elit. Aenean commodo ligula eget dolor. Aenean massa. Cum sociis natoque penatibus et magnis dis parturient montes, nascetur ridiculus mus.<\/p>\n<p><strong>XY Media<\/strong>\u00a0Website: <a href=\"http:\/\/www.wikipedia.com\">http:\/\/www.wikipedia.com<\/a><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-av_toggle-c8223143fd2b2dea398f9d16b5b57ec6'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{T\u00fcm\u00fc} \"  ><p data-fake-id='#toggle-id-2' class='toggler   '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-2'>Our Task<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-2' class='toggle_wrap  '  ><div class='toggle_content invers-color '  itemprop=\"text\" ><p><strong>Task<\/strong><\/p>\n<p>Lorem ipsum dolor sit amet, consectetuer adipiscing elit. Aenean commodo ligula eget dolor. Aenean massa. Cum sociis natoque penatibus et magnis dis parturient montes, nascetur ridiculus mus. Donec quam felis, ultricies nec, pellentesque eu, pretium quis, sem. Nulla consequat massa quis enim. Donec pede justo, fringilla vel, aliquet nec, vulputate eget, arcu.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-av_toggle-2c17499b25643600a837c292c055019f'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{T\u00fcm\u00fc} \"  ><p data-fake-id='#toggle-id-3' class='toggler   '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-3'>Skills Involved<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-3' class='toggle_wrap  '  ><div class='toggle_content invers-color '  itemprop=\"text\" ><p><strong>Skills<\/strong><\/p>\n<ul>\n<li>Photoshop<\/li>\n<li>Indesign<\/li>\n<li>HTML<\/li>\n<li>CSS<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/section>\n<\/div><\/p><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_1'  class='avia-section av-av_section-860e02eef87feb9b2e0751f470f2bac1 alternate_color avia-section-default avia-shadow  avia-builder-el-5  el_after_av_one_third  avia-builder-el-last  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-46'><div class='entry-content-wrapper clearfix'>\n<section  class='av_textblock_section av-av_textblock-e9dae3e5b2541c4b73533e030c1212d3'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h4 style=\"text-align: center;\">Most Recent Entries<\/h4>\n<\/div><\/section>\n<div  class='hr av-av_hr-4a566f4a73ae78223e1997276585dc3a hr-short  avia-builder-el-7  el_after_av_textblock  el_before_av_portfolio  avia-builder-el-last  hr-center'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div  id=\"av-sc-portfolio-1\"  class=' grid-sort-container isotope   no_margin-container with-excerpt-container grid-total-even grid-col-4 grid-links-' data-portfolio-id='1'><div data-ajax-id='46' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-46 grid-entry-overview grid-loop-1 grid-parity-odd  css_sort html_sort psd_sort  av_one_fourth first default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/dirisukilisesi.org\/index.php\/portfolio-item\/slider-two-third\/\" title='Single Portfolio: 2\/3 Slider'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" width=\"260\" height=\"185\" src=\"https:\/\/dirisukilisesi.org\/wp-content\/uploads\/2012\/04\/1-260x185.jpg\" class=\"wp-image-313 avia-img-lazy-loading-not-313 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/dirisukilisesi.org\/index.php\/portfolio-item\/slider-two-third\/' title='Single Portfolio: 2\/3 Slider'>Single Portfolio: 2\/3 Slider<\/a><\/h3><\/header><div class='grid-entry-excerpt entry-content'  itemprop=\"text\" >Excerpt goes here!<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='2272' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-2272 grid-entry-overview grid-loop-2 grid-parity-even  css_sort psd_sort  av_one_fourth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/dirisukilisesi.org\/index.php\/portfolio-item\/lorem-ipsum\/\" title='Single Portfolio: 2\/3 Gallery'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" width=\"260\" height=\"185\" src=\"https:\/\/dirisukilisesi.org\/wp-content\/uploads\/2012\/04\/013-260x185.jpg\" class=\"wp-image-314 avia-img-lazy-loading-not-314 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/dirisukilisesi.org\/index.php\/portfolio-item\/lorem-ipsum\/' title='Single Portfolio: 2\/3 Gallery'>Single Portfolio: 2\/3 Gallery<\/a><\/h3><\/header><div class='grid-entry-excerpt entry-content'  itemprop=\"text\" >wind\/earth<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='2271' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-2271 grid-entry-overview grid-loop-3 grid-parity-odd  css_sort html_sort  av_one_fourth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/dirisukilisesi.org\/index.php\/portfolio-item\/portfolio-big\/\" title='Single Portfolio: Big Slider'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" width=\"260\" height=\"185\" src=\"https:\/\/dirisukilisesi.org\/wp-content\/uploads\/2012\/04\/014-260x185.jpg\" class=\"wp-image-315 avia-img-lazy-loading-not-315 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/dirisukilisesi.org\/index.php\/portfolio-item\/portfolio-big\/' title='Single Portfolio: Big Slider'>Single Portfolio: Big Slider<\/a><\/h3><\/header><div class='grid-entry-excerpt entry-content'  itemprop=\"text\" >fire\/water<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='2273' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-2273 grid-entry-overview grid-loop-4 grid-parity-even  post-entry-last  html_sort photography_sort video_sort  av_one_fourth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/dirisukilisesi.org\/index.php\/portfolio-item\/vimeo-video\/\" title='Single Portfolio: Fullscreen Slider'  data-rel='grid-1' class='grid-image avia-hover-fx'> <\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/dirisukilisesi.org\/index.php\/portfolio-item\/vimeo-video\/' title='Single Portfolio: Fullscreen Slider'>Single Portfolio: Fullscreen Slider<\/a><\/h3><\/header><div class='grid-entry-excerpt entry-content'  itemprop=\"text\" >Add what you want!<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_1'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-46'><div class='entry-content-wrapper clearfix'>\n","protected":false},"excerpt":{"rendered":"<p>Excerpt goes here!<\/p>\n","protected":false},"featured_media":313,"comment_status":"open","ping_status":"open","template":"","tags":[],"portfolio_entries":[32,33,35],"class_list":["post-46","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-css","portfolio_entries-html","portfolio_entries-psd"],"_links":{"self":[{"href":"https:\/\/dirisukilisesi.org\/index.php\/wp-json\/wp\/v2\/portfolio\/46","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dirisukilisesi.org\/index.php\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/dirisukilisesi.org\/index.php\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/dirisukilisesi.org\/index.php\/wp-json\/wp\/v2\/comments?post=46"}],"version-history":[{"count":0,"href":"https:\/\/dirisukilisesi.org\/index.php\/wp-json\/wp\/v2\/portfolio\/46\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dirisukilisesi.org\/index.php\/wp-json\/wp\/v2\/media\/313"}],"wp:attachment":[{"href":"https:\/\/dirisukilisesi.org\/index.php\/wp-json\/wp\/v2\/media?parent=46"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dirisukilisesi.org\/index.php\/wp-json\/wp\/v2\/tags?post=46"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/dirisukilisesi.org\/index.php\/wp-json\/wp\/v2\/portfolio_entries?post=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}